{"id":16,"count":4,"description":"","link":"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/","name":"Dr. Frank Michitti","slug":"dr-frank-michitti","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Frank Michitti Archives - Lifetime Dental Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Frank Michitti Archives - Lifetime Dental Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifetime Dental Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/tag\\\/dr-frank-michitti\\\/\",\"url\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/tag\\\/dr-frank-michitti\\\/\",\"name\":\"Dr. Frank Michitti Archives - Lifetime Dental Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/tag\\\/dr-frank-michitti\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/tag\\\/dr-frank-michitti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Frank Michitti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/\",\"name\":\"Lifetime Dental Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lifetime.dental\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Frank Michitti Archives - Lifetime Dental Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/","og_locale":"en_US","og_type":"article","og_title":"Dr. Frank Michitti Archives - Lifetime Dental Blog","og_url":"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/","og_site_name":"Lifetime Dental Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/","url":"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/","name":"Dr. Frank Michitti Archives - Lifetime Dental Blog","isPartOf":{"@id":"https:\/\/www.lifetime.dental\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifetime.dental\/blog\/tag\/dr-frank-michitti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lifetime.dental\/blog\/"},{"@type":"ListItem","position":2,"name":"Dr. Frank Michitti"}]},{"@type":"WebSite","@id":"https:\/\/www.lifetime.dental\/blog\/#website","url":"https:\/\/www.lifetime.dental\/blog\/","name":"Lifetime Dental Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifetime.dental\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.lifetime.dental\/blog\/wp-json\/wp\/v2\/tags\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifetime.dental\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lifetime.dental\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lifetime.dental\/blog\/wp-json\/wp\/v2\/posts?tags=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}